{"id":443,"date":"2019-01-30T10:27:53","date_gmt":"2019-01-30T10:27:53","guid":{"rendered":"https:\/\/demo.harutheme.com\/pangja\/?page_id=443"},"modified":"2024-10-27T12:19:03","modified_gmt":"2024-10-27T11:19:03","slug":"contact","status":"publish","type":"page","link":"https:\/\/streetaix.fr\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1548846847156{padding-bottom: 8% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_3&#8243; text=&#8221;I.C1101&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723390401019{padding-bottom: 4% !important;}&#8221;][vc_column_text css=&#8221;&#8221;]I.C1101 est une identit\u00e9 audacieuse inspir\u00e9e par la galaxie centrale du superamas Abell 2029. Nous promouvons la mode comme expression artistique en collaborant avec des talents locaux, utilisant des mat\u00e9riaux \u00e9cologiques. Nos services personnalis\u00e9s encouragent des actions communes et des \u00e9v\u00e9nements o\u00f9 vous \u00eates au centre.[\/vc_column_text]                        <div class=\"  \">\n                <div class=\"footer-contact-shortcode-wrap style_2 \">\n    <div class=\"footer-contact-content\">\n        <ul class=\"contact-information\">\n                                <li>\n                        <span class=\"contact-icon fas fa-phone\"><\/span>\n                        <span class=\"contact-label\">T\u00e9l\u00e9phone<\/span>\n                        <span class=\"contact-description\">06 85 90 25 04<\/span>\n                    <\/li>\n                                <li>\n                        <span class=\"contact-icon fas fa-envelope\"><\/span>\n                        <span class=\"contact-label\">Email<\/span>\n                        <span class=\"contact-description\">i.c1101contact@gmail.com <\/span>\n                    <\/li>\n                    <\/ul>\n    <\/div>\n<\/div>            <\/div>\n                    [\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_3&#8243; text=&#8221;Message&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723403177592{padding-bottom: 4% !important;}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f182-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"182\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/443#wpcf7-f182-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"182\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f182-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"contact-form\">\n<div class=\"contact-name\">\n<h5 class=\"contact-title\">Votre Nom<span>*<\/span><\/h5>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/div>\n<\/div>\n<div class=\"contact-email\">\n<h5 class=\"contact-title\">Votre email<span>*<\/span><\/h5>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/div>\n<\/div>\n<div class=\"contact-subject\">\n<h5 class=\"contact-title\">Sujet<\/h5>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span><\/div>\n<\/div>\n<div class=\"contact-message\">\n<h5 class=\"contact-title\">Message<\/h5>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"\" name=\"your-message\"><\/textarea><\/span><\/div>\n<\/div>\n<div class=\"contact-submit\">\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoi Message\" \/>\n<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"85\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1548846847156{padding-bottom: 8% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_3&#8243; text=&#8221;I.C1101&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1723390401019{padding-bottom: 4% !important;}&#8221;][vc_column_text css=&#8221;&#8221;]I.C1101 est une identit\u00e9 audacieuse inspir\u00e9e par la galaxie centrale du superamas Abell 2029. Nous promouvons la mode comme expression artistique en collaborant avec des talents locaux, utilisant des mat\u00e9riaux \u00e9cologiques. Nos services personnalis\u00e9s encouragent des actions communes et des \u00e9v\u00e9nements o\u00f9 vous \u00eates [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-443","page","type-page","status-publish","hentry","clearfix"],"_links":{"self":[{"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/pages\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":0,"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/pages\/443\/revisions"}],"wp:attachment":[{"href":"https:\/\/streetaix.fr\/index.php\/wp-json\/wp\/v2\/media?parent=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}